{"id":554,"date":"2023-05-18T09:56:40","date_gmt":"2023-05-18T09:56:40","guid":{"rendered":"https:\/\/cryptobutthead.com\/?p=554"},"modified":"2023-05-23T20:39:39","modified_gmt":"2023-05-23T20:39:39","slug":"yall-wont-believe-what-this-ledger-gadget-is-up-to-now","status":"publish","type":"post","link":"https:\/\/cryptobutthead.com\/de\/ledger-will-mit-dem-kopf-durch-die-wallet\/","title":{"rendered":"Man glaubt es nicht, Ledger will mit dem Kopf durch die Wallet"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-565 alignleft\" src=\"https:\/\/cryptobutthead.com\/wp-content\/uploads\/2023\/05\/cbh_wallet_03-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/cryptobutthead.com\/wp-content\/uploads\/2023\/05\/cbh_wallet_03-300x300.jpg 300w, https:\/\/cryptobutthead.com\/wp-content\/uploads\/2023\/05\/cbh_wallet_03-150x150.jpg 150w, https:\/\/cryptobutthead.com\/wp-content\/uploads\/2023\/05\/cbh_wallet_03-768x768.jpg 768w, https:\/\/cryptobutthead.com\/wp-content\/uploads\/2023\/05\/cbh_wallet_03.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<div class=\"flex flex-grow flex-col gap-3\">\n<div class=\"min-h-[20px] flex flex-col items-start gap-4 whitespace-pre-wrap break-words\">\n<div class=\"markdown prose w-full break-words dark:prose-invert dark\">\n<p>[CryptoButthead.com , msch , 18. Mai 2023] Es geht weiter mit Ledger \u2026 verwirrender als ein Feldweg bei Nacht. Ledger, die Gro\u00dfen in dem Gesch\u00e4ft mit den Hardware-Wallets, r\u00fchren mit ihrem neumodischen Dingens namens Ledger Recover geh\u00f6rig im Wespennest. Das soll den Leuten helfen, ihren Seed-Phrase wiederzukriegen \u2013 das sind die Zauberworte, die eure Krypto-Wallet \u00f6ffnen \u2013 indem sie sich bei Ledger hierf\u00fcr sp\u00e4ter in einem solchen Falle ausweisen k\u00f6nnen.<\/p>\n<p>Dieser Service wurde in L\u00e4ndern der Europ\u00e4ischen Union, Gro\u00dfbritannien, Kanada und unserer guten alten USA eingef\u00fchrt. Um es zu nutzen, m\u00fcssen die Leute ihren Pass oder Ausweis zur \u00dcberpr\u00fcfung \u00fcbermitteln. Klingt einfach, oder?<\/p>\n<p>Aber noch verwirrender als ein blindes Huhn im Kornfeld sein kann, nehmen sie eure Seed-Phrase und zerst\u00fcckeln sie in drei Teile, irgendwie wie ein digitaler Gl\u00fcckskeks. Dann schicken sie jedes dieser Teile an jeweils drei unterschiedliche Empf\u00e4nger: Coincover, Ledger und einen anderen mysteri\u00f6sen Escrow Backup-Service. Um eure Phrase zur\u00fcckzubekommen, m\u00fcsst ihr einen Ausweischeck bestehen und zwei der drei Unternehmen m\u00fcssen die Teile an euer Ledger-Ger\u00e4t zur\u00fcckschicken. Sobald sie zusammengef\u00fchrt sind, wird euch eure Phrase enth\u00fcllt.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-566 alignright\" src=\"https:\/\/cryptobutthead.com\/wp-content\/uploads\/2023\/05\/cbh_wallet_02-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/cryptobutthead.com\/wp-content\/uploads\/2023\/05\/cbh_wallet_02-300x300.jpg 300w, https:\/\/cryptobutthead.com\/wp-content\/uploads\/2023\/05\/cbh_wallet_02-150x150.jpg 150w, https:\/\/cryptobutthead.com\/wp-content\/uploads\/2023\/05\/cbh_wallet_02-768x768.jpg 768w, https:\/\/cryptobutthead.com\/wp-content\/uploads\/2023\/05\/cbh_wallet_02.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Aber nicht jeder ist mit diesem Plan gl\u00fccklich wie eine Kuh auf dem Gras. Einige Leute machen sich Sorgen \u00fcber Risiken wie z.B. die Unternehmen, k\u00f6nnen sich gegen euch verb\u00fcnden oder mit den Regierungen gemeinsame Sache, Identit\u00e4tsdiebstahl und die Schaffung eines Systems, das zu viel \u00fcber euch wei\u00df, ganz genau wie bei einer richtigen Bank.<\/p>\n<p>Dieser Kerl, Mudit Gupta, ein hohes Tier bei Polygon, nannte es eine \u201eentsetzliche Idee\u201c. Und ein anderer Nutzer, verglich es mit der Erstellung eines Bankkontos, nur komplizierter. Selbst Emin G\u00fcn Sirer, kluger Kopf bei Ava Labs, war nicht begeistert davon.<\/p>\n<p>Und vergessen wir nicht die Privatsph\u00e4re. Viele Leute sind nicht gerade begeistert von der Idee, dass ihre privaten Schl\u00fcssel durch Ledgers API preisgegeben werden k\u00f6nnten. Anton Bukov von 1inch und Changpeng Zhao von Binance geh\u00f6ren zu denen, die die Alarmglocken l\u00e4uten h\u00f6ren.<\/p>\n<p>All dieser Rummel betrifft im Moment nur Besitzer von Ledger\u2019s Nano X Wallets, aber man\u00a0 plant in der Zukunft auch die Nano S Plus und Stax Wallets einzubeziehen. Man begrenzt die Anzahl der Versuche, die man machen kann, um die Seed-Phrase zur\u00fcckzubekommen.<\/p>\n<p>Trotz des ganzen Wirbels halten die Chefs von Ledger in einer Twitter-Diskussion an ihrer Erneuerung fest. Ledger CEO Pascal Gauthier, so stolz wie ein Hahn im H\u00fchnerstall, behauptete: \u201eSo werden wir die n\u00e4chsten Hunderte von Millionen von Menschen in die Krypto-Welt einsteigen lassen k\u00f6nnen. Es tut mir leid, aber das St\u00fcck Papier geh\u00f6rt der Vergangenheit an und Ledger Recover ist die Zukunft.\u201c Nun, das werden wir ja noch sehen, oder?<\/p>\n<p>\u00a0<\/p>\n<p><strong>Haftungsausschluss:<\/strong> Yo, Leute, das ist meine Meinung. Vergesst nicht, cool zu bleiben und ein bisschen gesunden Menschenverstand einzusetzen, wenn ihr Artikel lest und euch eine eigene Meinung bildet. Und denkt dran, wenn es ums Investieren geht, dann ist das immer, irgendwie, mit extremen Risiken verbunden. Wenn ihr euch nicht auskennt, dann fragt jemanden, der mehr Ahnung hat!<\/p>\n<hr noshade=\"noshade\" \/>\n<table border=\"0\">\n<tbody>\n<tr>\n<td><iframe style=\"width: 120px; height: 240px;\" src=\"\/\/ws-eu.amazon-adsystem.com\/widgets\/q?ServiceVersion=20070822&OneJS=1&Operation=GetAdHtml&MarketPlace=DE&source=ss&ref=as_ss_li_til&ad_type=product_link&tracking_id=gatex0250-21&language=de_DE&marketplace=amazon&region=DE&placement=B08KWB9QTZ&asins=B08KWB9QTZ&linkId=8ffc4d41ed9b3acc06527b330c8e3ebf&show_border=true&link_opens_new_window=true\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" sandbox=\"allow-popups allow-scripts allow-modals allow-forms allow-same-origin\"><\/iframe><\/td>\n<td><iframe style=\"width: 120px; height: 240px;\" src=\"\/\/ws-eu.amazon-adsystem.com\/widgets\/q?ServiceVersion=20070822&OneJS=1&Operation=GetAdHtml&MarketPlace=DE&source=ss&ref=as_ss_li_til&ad_type=product_link&tracking_id=gatex0250-21&language=de_DE&marketplace=amazon&region=DE&placement=B00R6MKDDE&asins=B00R6MKDDE&linkId=547fd8c5d921a1768820bc5d7fccb885&show_border=true&link_opens_new_window=true\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" sandbox=\"allow-popups allow-scripts allow-modals allow-forms allow-same-origin\"><\/iframe><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<hr noshade=\"noshade\" \/>\n<div class=\"flex flex-grow flex-col gap-3\">\n<div class=\"min-h-[20px] flex flex-col items-start gap-4 whitespace-pre-wrap\">\n<div class=\"markdown prose w-full break-words dark:prose-invert dark\">\n<p>Yo Leute, wenn euch der Artikel gefallen hat und ihr gerne etwas zur\u00fcckgeben m\u00f6chtet, dann k\u00f6nnt ihr uns gerne eine kleine Spende in Satoshis\/Bitcoin schicken.<\/p>\n<p>Wir sind nicht die reichsten Typen, aber jede kleine Spende hilft uns dabei, diese Website am Laufen zu halten und weitere Artikel wie diesen zu schreiben.<\/p>\n<p>Also, wenn ihr uns ein paar Sats zukommen lassen wollt, dann schickt diese einfach an unsere Bitcoin-Adresse, die ihr unten findet oder nutzt den QR Code.<\/p>\n<p>Bitcoin-Adresse:\u00a0bc1qcs35vjdsdxgqhugg05mh469ngrezv2s38fajn0<\/p>\n<p>Wir danken euch im Voraus f\u00fcr eure Unterst\u00fctzung und f\u00fcr das Lesen unseres Artikels. Ihr seid die Besten!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-97\" src=\"https:\/\/cryptobutthead.com\/wp-content\/uploads\/2023\/04\/donate-300x300.png\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/cryptobutthead.com\/wp-content\/uploads\/2023\/04\/donate-300x300.png 300w, https:\/\/cryptobutthead.com\/wp-content\/uploads\/2023\/04\/donate-150x150.png 150w, https:\/\/cryptobutthead.com\/wp-content\/uploads\/2023\/04\/donate.png 340w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<\/div>\n<\/div>\n<\/div>\n<hr noshade=\"noshade\" size=\"1\" \/>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>[CryptoButthead.com , msch , 18. Mai 2023] Es geht weiter mit Ledger \u2026 verwirrender als ein Feldweg bei Nacht. Ledger, die Gro\u00dfen in dem Gesch\u00e4ft mit den Hardware-Wallets, r\u00fchren mit ihrem neumodischen Dingens namens Ledger Recover geh\u00f6rig im Wespennest. Das soll den Leuten helfen, ihren Seed-Phrase wiederzukriegen \u2013 das sind die Zauberworte, die eure Krypto-Wallet &#8230; <a title=\"Man glaubt es nicht, Ledger will mit dem Kopf durch die Wallet\" class=\"read-more\" href=\"https:\/\/cryptobutthead.com\/de\/ledger-will-mit-dem-kopf-durch-die-wallet\/\">Read more<span class=\"screen-reader-text\">Man glaubt es nicht, Ledger will mit dem Kopf durch die Wallet<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[306,302,305,159,303,298,301,265,299,304,288,300],"class_list":["post-554","post","type-post","status-publish","format-standard","hentry","category-verschiedenes","tag-1inch","tag-api-exposure","tag-ava-labs","tag-binance","tag-crypto-security","tag-hardware-wallets","tag-identity-verification","tag-ledger","tag-ledger-recover","tag-polygon","tag-privacy-concerns","tag-seed-phrase-recovery"],"aioseo_notices":[],"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"cryptobuttheadxadmin","author_link":"https:\/\/cryptobutthead.com\/de\/author\/cryptobuttheadxadmin\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/cryptobutthead.com\/de\/category\/verschiedenes\/\" rel=\"category tag\">Verschiedenes<\/a>","rttpg_excerpt":"[CryptoButthead.com , msch , 18. Mai 2023] Es geht weiter mit Ledger \u2026 verwirrender als ein Feldweg bei Nacht. Ledger, die Gro\u00dfen in dem Gesch\u00e4ft mit den Hardware-Wallets, r\u00fchren mit ihrem neumodischen Dingens namens Ledger Recover geh\u00f6rig im Wespennest. Das soll den Leuten helfen, ihren Seed-Phrase wiederzukriegen \u2013 das sind die Zauberworte, die eure Krypto-Wallet&hellip;","_links":{"self":[{"href":"https:\/\/cryptobutthead.com\/de\/wp-json\/wp\/v2\/posts\/554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptobutthead.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptobutthead.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptobutthead.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptobutthead.com\/de\/wp-json\/wp\/v2\/comments?post=554"}],"version-history":[{"count":2,"href":"https:\/\/cryptobutthead.com\/de\/wp-json\/wp\/v2\/posts\/554\/revisions"}],"predecessor-version":[{"id":630,"href":"https:\/\/cryptobutthead.com\/de\/wp-json\/wp\/v2\/posts\/554\/revisions\/630"}],"wp:attachment":[{"href":"https:\/\/cryptobutthead.com\/de\/wp-json\/wp\/v2\/media?parent=554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptobutthead.com\/de\/wp-json\/wp\/v2\/categories?post=554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptobutthead.com\/de\/wp-json\/wp\/v2\/tags?post=554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}